{"id":15739,"date":"2025-08-20T17:16:21","date_gmt":"2025-08-20T15:16:21","guid":{"rendered":"https:\/\/www.archieinteriors.com\/brands\/moltenic\/"},"modified":"2026-08-24T09:36:24","modified_gmt":"2026-08-24T07:36:24","slug":"moltenic","status":"publish","type":"wpbdp_listing","link":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/","title":{"rendered":"Molteni&amp;C"},"content":{"rendered":" \n <div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">  \n <p> From the dream of an artisan workshop founded in Giussano in 1934, the <strong data-start=\"560\" data-end=\"579\"> Molteni brand <\/strong> is over time he has become one of the most important voices leading figures in <strong data-start=\"636\" data-end=\"661\"> international design <\/strong>. A story that combines passion, innovation and ability to transform the most noble in quality furnishings absolute, bringing authenticity to the world of <strong data-start=\"824\" data-end=\"841\"> Made in Italy <\/strong>. <\/p> \n <p data-start=\"846\" data-end=\"1266\"> Today the <strong data-start=\"854\" data-end=\"873\"> Molteni&amp;C <\/strong> brand is synonymous with excellence and innovation in <strong data-start=\"918\" data-end=\"943\"> designer furniture <\/strong>: collections ranging from <strong data-start=\"972\" data-end=\"1049\"> modern kitchens, luxury sofas and armchairs, tables and furnishing accessories <\/strong>, up to <strong data-start=\"1059\" data-end=\"1088\"> living systems and bookcases <\/strong>, conceived as integrated and flexible solutions for making the most of domestic spaces. Each project arises from collaboration with world-famous architects and designers. <\/p> \n <p data-start=\"1268\" data-end=\"1497\"> Molteni design is based on an integrated approach, where <strong data-start=\"1327\" data-end=\"1407\"> technological research, careful selection of materials and design culture <\/strong> come together to create functional, sophisticated and sustainable furnishing solutions. <\/p> \n <p data-start=\"1499\" data-end=\"1819\"> Recognized with the prestigious <strong data-start=\"1531\" data-end=\"1563\"> Compasso d&rsquo;Oro for lifetime achievement <\/strong>, the company testifies to its leading role in the history of <strong data-start=\"1632\" data-end=\"1651\"> Italian design <\/strong>. With three generations and almost a century of experience, Molteni&amp;C continues to represent Italian excellence in the world, bringing its products to over 90 countries. <\/p> \n <h3> <strong> The iconic collections and products <\/strong> <\/h3> \n <p> <strong> Molteni&amp;C <\/strong> offers various collections that tell its vision of design. Among the most representative, the <strong> Heritage Collection <\/strong> , which enhances the works of Gio Ponti, the <strong> Landmark Collection <\/strong> , with fluid shapes and material interweavings, and the <strong> Timeout Collection <\/strong> , which reinterprets metal for indoor and outdoor spaces. <\/p> \n <p> Among the iconic and bestselling products that complete the identity of of the brand: <\/p> \n <ul> \n <li> <strong> Logos day systems and bookcases <\/strong>: signed by Vincent Van Duysen, it is a modular and versatile system that allows infinite configurations, with customizable modules and fine finishes in wood, glass, metal and lacquer. <\/li> \n <li> <strong> D.154.2 armchair <\/strong>: designed by Gio Ponti for the Planchart villa in Caracas, awarded as a symbol of Italian design. <\/li> \n <li> <strong> Sway sofas <\/strong>: modular system with an innovative design by Yabu Pushelberg. <\/li> \n <li> <strong> Palinfrasca sofa <\/strong>: homage to Luca Meda&#8217;s 1994 project, it reinterprets the essence of teak in a modern key. <\/li> \n <li> <strong> Ratio kitchen <\/strong>: by Vincent Van Duysen, metal lattice structure and fine materials for a warm and Mediterranean design. <\/li> \n <li> <strong> 655.1 \/ D.655.2 <\/strong>: cupboards and containers by Gio Ponti, with white hand-painted fronts and handles in fine woods, faithful re-edition of the original 1950 drawings kept in the Gio Ponti Archives. <\/li> \n <\/ul> \n <p> Download the <strong data-start=\"284\" data-end=\"311\"> Molteni catalog <\/strong> &nbsp;and discover modular systems for living rooms, equipped walls, walk-in wardrobes and bookcases, together with tables, sofas, armchairs and Made in Italy design furnishing accessories. <\/p> \n  <\/div><\/div> \n  \n\n  \n <h2 class=\"wp-block-heading\" style=\"font-size:22px\"> Molteni&amp;C Catalogs <\/h2> \n  \n\n  \n <div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> New Collection 2025 <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-New-Collection-2025-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img fetchpriority=\"high\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-New-Collection-2025-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C New Collection 2025\" class=\"wp-image-6041\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-New-Collection-2025-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-New-Collection-2025-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-New-Collection-2025-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Kitchen Collection 2025 <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Kitchen-Collection-2025-full-Catalog.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"> <img decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Kitchen-Collection-2025-full-Catalog.jpg\" alt=\"Immagine di copertina del catalogo Molteni&amp;C Kitchen Collection 2025\" class=\"wp-image-6039\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Kitchen-Collection-2025-full-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Kitchen-Collection-2025-full-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Kitchen-Collection-2025-full-Catalog.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Home 2025 <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2025-full-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2025-full-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C Home 2025 full Catalog\" class=\"wp-image-6037\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2025-full-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2025-full-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2025-full-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Home 2024 <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2024-full-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2024-full-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C Home 2024 full Catalog\" class=\"wp-image-6035\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2024-full-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2024-full-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Home-2024-full-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Dining <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Dining-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Dining-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C Dining Catalog\" class=\"wp-image-6033\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Dining-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Dining-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Dining-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Sofas <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sofas-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sofas-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C Sofas Catalog\" class=\"wp-image-6047\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sofas-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sofas-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sofas-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Sleeping <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sleeping-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sleeping-Catalog.jpg\" alt=\"Catalogo Molteni&amp;C Sleeping Catalog\" class=\"wp-image-6045\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sleeping-Catalog.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sleeping-Catalog-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Sleeping-Catalog.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  \n\n  \n <div class=\"wp-block-column is-vertically-aligned-stretch col-xs-6 col-sm-6 col-md-4 col-lg-3 is-layout-flow wp-block-column-is-layout-flow\">  \n <p class=\"has-text-align-center\"> Outdoor Catalog 2024 <\/p> \n  \n\n  \n <figure class=\"wp-block-image size-full\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Outdoor-Catalogue-2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> <img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"495\" src=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Outdoor-Catalogue-2024.jpg\" alt=\"Immagine di copertina del catalogo Molteni&amp;C Outdoor Catalogue 2024\" class=\"wp-image-6043\" srcset=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Outdoor-Catalogue-2024.jpg 350w, https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Outdoor-Catalogue-2024-212x300.jpg 212w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> <\/a> <\/figure> \n  \n\n  \n <p class=\"has-text-align-center\"> <a href=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2025\/08\/Catalogo-Molteni-C-Outdoor-Catalogue-2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Download <\/a> <\/p> \n  <\/div> \n  <\/div> \n  \n\n  \n <h2 class=\"wp-block-heading\" style=\"font-size:22px\"> Articles &#8211; News &#8211; Press Releases Molteni&amp;C <\/h2> \n  \n\n  \n <p> &nbsp; <\/p> \n ","protected":false},"excerpt":{"rendered":"<p>From the dream of an artisan workshop founded in Giussano in 1934, the Molteni brand is over time he has become one of the most important voices leading figures in international design . A story that combines passion, innovation and ability to transform the most noble in quality furnishings absolute, bringing authenticity to the world&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15947,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"wpbdp_category":[372,359,360],"wpbdp_tag":[],"class_list":["post-15739","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-home-furnishings","wpbdp_category-interior-design","wpbdp_category-kitchen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Molteni&amp;C | Made in Italy design furniture, kitchens &amp; sofas<\/title>\n<meta name=\"description\" content=\"Explore Molteni&amp;C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Molteni&amp;C | Made in Italy design furniture, kitchens &amp; sofas\" \/>\n<meta property=\"og:description\" content=\"Explore Molteni&amp;C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/\" \/>\n<meta property=\"og:site_name\" content=\"Archi &amp; Interiors\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-24T07:36:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/\",\"url\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/\",\"name\":\"Molteni&C | Made in Italy design furniture, kitchens & sofas\",\"isPartOf\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg\",\"datePublished\":\"2025-08-20T15:16:21+00:00\",\"dateModified\":\"2026-08-24T07:36:24+00:00\",\"description\":\"Explore Molteni&C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage\",\"url\":\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg\",\"contentUrl\":\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg\",\"width\":225,\"height\":225,\"caption\":\"Molteni&C brand logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.archieinteriors.com\/en\/home-nuova\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Molteni&amp;C\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#website\",\"url\":\"https:\/\/www.archieinteriors.com\/en\/\",\"name\":\"Archi & Interiors\",\"description\":\"Archi &amp; Interiors Magazine\",\"publisher\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.archieinteriors.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#organization\",\"name\":\"Archi & Interiors\",\"url\":\"https:\/\/www.archieinteriors.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2024\/07\/cropped-customcolor_logo_customcolor_background.png\",\"contentUrl\":\"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2024\/07\/cropped-customcolor_logo_customcolor_background.png\",\"width\":937,\"height\":550,\"caption\":\"Archi & Interiors\"},\"image\":{\"@id\":\"https:\/\/www.archieinteriors.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Molteni&C | Made in Italy design furniture, kitchens & sofas","description":"Explore Molteni&C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/","og_locale":"en_US","og_type":"article","og_title":"Molteni&C | Made in Italy design furniture, kitchens & sofas","og_description":"Explore Molteni&C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.","og_url":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/","og_site_name":"Archi &amp; Interiors","article_modified_time":"2026-08-24T07:36:24+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/","url":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/","name":"Molteni&C | Made in Italy design furniture, kitchens & sofas","isPartOf":{"@id":"https:\/\/www.archieinteriors.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage"},"image":{"@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg","datePublished":"2025-08-20T15:16:21+00:00","dateModified":"2026-08-24T07:36:24+00:00","description":"Explore Molteni&C: Made in Italy design furniture, sofas, kitchens and bookcases. Official catalogs and collections by Gio Ponti and Vincent Van Duysen.","breadcrumb":{"@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#primaryimage","url":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg","contentUrl":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2026\/03\/logo-brand-molteni-C.jpg","width":225,"height":225,"caption":"Molteni&C brand logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.archieinteriors.com\/en\/brand\/moltenic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.archieinteriors.com\/en\/home-nuova\/"},{"@type":"ListItem","position":2,"name":"Molteni&amp;C"}]},{"@type":"WebSite","@id":"https:\/\/www.archieinteriors.com\/en\/#website","url":"https:\/\/www.archieinteriors.com\/en\/","name":"Archi & Interiors","description":"Archi &amp; Interiors Magazine","publisher":{"@id":"https:\/\/www.archieinteriors.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.archieinteriors.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.archieinteriors.com\/en\/#organization","name":"Archi & Interiors","url":"https:\/\/www.archieinteriors.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archieinteriors.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2024\/07\/cropped-customcolor_logo_customcolor_background.png","contentUrl":"https:\/\/www.archieinteriors.com\/wp-content\/uploads\/2024\/07\/cropped-customcolor_logo_customcolor_background.png","width":937,"height":550,"caption":"Archi & Interiors"},"image":{"@id":"https:\/\/www.archieinteriors.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_listing\/15739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/comments?post=15739"}],"version-history":[{"count":1,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_listing\/15739\/revisions"}],"predecessor-version":[{"id":24840,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_listing\/15739\/revisions\/24840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/media\/15947"}],"wp:attachment":[{"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/media?parent=15739"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_category?post=15739"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/www.archieinteriors.com\/en\/wp-json\/wp\/v2\/wpbdp_tag?post=15739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}